{"id":1551,"date":"2019-06-10T08:55:43","date_gmt":"2019-06-10T11:55:43","guid":{"rendered":"https:\/\/phelcom.com\/?p=1551"},"modified":"2023-06-01T16:53:45","modified_gmt":"2023-06-01T19:53:45","slug":"inteligencia-artificial-auxilia-os-oftalmologistas","status":"publish","type":"post","link":"https:\/\/phelcom.com\/pt-br\/blog\/saude\/inteligencia-artificial-auxilia-os-oftalmologistas\/","title":{"rendered":"Como a intelig\u00eancia artificial auxilia os oftalmologistas"},"content":{"rendered":"<p>De fato, o n\u00famero expressivo de <a href=\"https:\/\/phelcom.com\/blog\/inteligencia-artificial-na-oftalmologia\/\">pesquisas com intelig\u00eancia artificial (IA)<\/a> e seus resultados promissores apontam para um caminho altamente tecnol\u00f3gico na \u00e1rea de medicina. Mais do que isso, o desenvolvimento de softwares cada vez mais inovadores prometem revolucionar o setor ao entregar mais qualidade, acessibilidade, agilidade, efetividade e redu\u00e7\u00e3o de custos tanto para pacientes quanto para os profissionais e institui\u00e7\u00f5es envolvidas.<\/p>\n<p>Com o r\u00e1pido avan\u00e7o da IA, j\u00e1 existem d\u00favidas sobre o papel futuro do profissional de sa\u00fade. De fato, muitas fun\u00e7\u00f5es e atribui\u00e7\u00f5es deixar\u00e3o de existir. Mas, por outro lado, novas responsabilidades chegar\u00e3o. Isto \u00e9, os especialistas jamais ser\u00e3o substitu\u00eddos pela tecnologia, como dizem algumas correntes de pensamento.<\/p>\n<p>Na \u00e1rea de oftalmologia, uma pesquisa realizada pelo time de IA do Google comprovou que oftalmologistas e algoritmos s\u00e3o mais eficazes quando trabalham juntos, e n\u00e3o separadamente. O <a href=\"https:\/\/www.aaojournal.org\/article\/S0161-6420(18)31575-6\/fulltext\">trabalho foi publicado pela revista Ophthalmology<\/a>, da Academia Americana de Oftalmologia.<\/p>\n<p>Por isso, vamos falar neste post sobre como foi desenvolvido esse estudo, que confirma: a intelig\u00eancia artificial auxilia os oftalmologistas.<\/p>\n<h2>A pesquisa<\/h2>\n<p>O estudo elaborado pelo time de IA do Google buscou verificar se o diagn\u00f3stico realizado em conjunto por um algoritmo inteligente e por um m\u00e9dico \u00e9 mais efetivo do que apenas pelo software ou pelo especialista \u2013 neste caso, ambos sozinhos.<\/p>\n<p>A pesquisa contou com 10 oftalmologistas de diferentes especializa\u00e7\u00f5es, que classificaram aproximadamente 1,8 mil imagens dos olhos de pacientes com retinopatia diab\u00e9tica, desde o grau leve at\u00e9 o grave.<\/p>\n<p>Os testes foram divididos em tr\u00eas etapas:<\/p>\n<ul>\n<li>Sem o algoritmo;<\/li>\n<li>Com o grau do algoritmo;<\/li>\n<li>Com o algoritmo mais uma explica\u00e7\u00e3o do por que o algoritmo produziu esse grau.<\/li>\n<\/ul>\n<h2>Os resultados<\/h2>\n<p>De fato, os diagn\u00f3sticos apresentados pelos m\u00e9dicos foram mais precisos com o aux\u00edlio da IA \u2013 etapas 2 e 3. Al\u00e9m disso, notou-se uma melhora na confian\u00e7a do oftalmologista no seu pr\u00f3prio diagn\u00f3stico.<\/p>\n<p>Neste caso, a tecnologia teve o efeito de \u201csegunda opini\u00e3o\u201d. Ou seja, um diagn\u00f3stico mais efetivo, como se fosse o parecer de outro m\u00e9dico.<\/p>\n<p><a href=\"https:\/\/phelcom.com\/wp-content\/uploads\/2019\/06\/intelig\u00eancia-artificial-auxilia-oftalmologistas-2.jpg\" data-lbwps-width=\"2313\" data-lbwps-height=\"1376\" data-lbwps-srcsmall=\"https:\/\/phelcom.com\/wp-content\/uploads\/2019\/06\/intelig\u00eancia-artificial-auxilia-oftalmologistas-2-300x178.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-1552\" src=\"https:\/\/phelcom.com\/wp-content\/uploads\/2019\/06\/intelig\u00eancia-artificial-auxilia-oftalmologistas-2-1024x609.jpg\" alt=\"intelig\u00eancia artificial auxilia oftalmologistas\" width=\"1024\" height=\"609\" srcset=\"https:\/\/phelcom.com\/wp-content\/uploads\/2019\/06\/intelig\u00eancia-artificial-auxilia-oftalmologistas-2-1024x609.jpg 1024w, https:\/\/phelcom.com\/wp-content\/uploads\/2019\/06\/intelig\u00eancia-artificial-auxilia-oftalmologistas-2-600x357.jpg 600w, https:\/\/phelcom.com\/wp-content\/uploads\/2019\/06\/intelig\u00eancia-artificial-auxilia-oftalmologistas-2-300x178.jpg 300w, https:\/\/phelcom.com\/wp-content\/uploads\/2019\/06\/intelig\u00eancia-artificial-auxilia-oftalmologistas-2-768x457.jpg 768w, https:\/\/phelcom.com\/wp-content\/uploads\/2019\/06\/intelig\u00eancia-artificial-auxilia-oftalmologistas-2-1080x642.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/p>\n<h2>Google: trabalho anterior criou tecnologia que detecta retinopatia diab\u00e9tica e edema macular<\/h2>\n<h2><\/h2>\n<p>A iniciativa de realizar esta pesquisa partiu ap\u00f3s um estudo anterior feito pela startup Verily, do Google. Nele, desenvolveu-se uma <a href=\"https:\/\/phelcom.com\/blog\/nova-inteligencia-artificial-do-google-detecta-doencas\/\">intelig\u00eancia artificial que consegue identificar retinopatia diab\u00e9tica e edema macular diab\u00e9tico<\/a> ao analisar fotos de pessoas com sinais dessas doen\u00e7as.<\/p>\n<p>Apesar dos resultados iniciais promissores, este ainda \u00e9 apenas o in\u00edcio do trabalho. Isso porque \u00e9 necess\u00e1rio um grande conjunto de dados, com enorme variedade, para representar o mundo real. Assim sendo, ser\u00e1 poss\u00edvel conseguir diagn\u00f3sticos cada vez mais precisos.<\/p>\n<p>No Brasil, a startup <a href=\"https:\/\/phelcom.com\/\">Phelcom Technologies<\/a> desenvolveu um\u00a0<a href=\"https:\/\/revistagalileu.globo.com\/Ciencia\/Saude\/noticia\/2019\/06\/novo-aparelho-para-celular-diagnostica-doencas-nos-olhos-custo-baixo.html\">retin\u00f3grafo port\u00e1til\u00a0<\/a>para preven\u00e7\u00e3o e diagn\u00f3stico de doen\u00e7as na retina. O Phelcom Eyer funciona acoplado a um smartphone com c\u00e2mera de alta resolu\u00e7\u00e3o. Ele captura a imagem do fundo do olho, realizando o exame de retina. Integrado a uma plataforma online, envia automaticamente os dados para o laudo de um especialista.<\/p>\n<p>Dessa forma, a Phelcom possui um banco de dados cada vez maior com imagens de retinas afetadas por diversas doen\u00e7as. Dentre elas, retinopatia diab\u00e9tica e edema macular diab\u00e9tico. Com isso, tamb\u00e9m poder\u00e1 contribuir com algoritmos inteligentes em busca de padr\u00f5es relacionados \u00e0s principais doen\u00e7as.<\/p>\n<h2>Conclus\u00e3o<\/h2>\n<p>Conforme as novas tecnologias de intelig\u00eancia artificial s\u00e3o treinadas, os algoritmos inteligentes podem auxiliar na democratiza\u00e7\u00e3o do acesso a exames de retinopatia diab\u00e9tica e outras doen\u00e7as oculares. Sem d\u00favida, o sistema aperfei\u00e7oado tamb\u00e9m ajudar\u00e1 na redu\u00e7\u00e3o de custos e em um processo mais efetivo de triagem.<\/p>\n<p>Portanto, sim: a intelig\u00eancia artificial auxilia os oftalmologistas.<\/p>\n<p>Intelig\u00eancia artificial na oftalmologia \u00e9 um assunto que interessa voc\u00ea? Ent\u00e3o, assine o nosso blog e acompanhe as principais novidades na \u00e1rea.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uma pesquisa realizada pelo setor de Intelig\u00eancia Artificial do Google comprovou que oftalmologistas e algoritmos s\u00e3o mais eficazes quando trabalham juntos, e n\u00e3o separadamente. Entenda como esse estudo foi desenvolvido neste post.<\/p>\n","protected":false},"author":3,"featured_media":1553,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[107],"tags":[],"class_list":["post-1551","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-saude"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Como a intelig\u00eancia artificial auxilia os oftalmologistas - PHELCOM Technologies<\/title>\n<meta name=\"description\" content=\"Uma pesquisa realizada pelo Google comprovou que a intelig\u00eancia artificial auxilia os oftalmologistas. Entenda esse estudo e os resultados neste post.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/phelcom.com\/pt-br\/blog\/saude\/inteligencia-artificial-auxilia-os-oftalmologistas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Como a intelig\u00eancia artificial auxilia os oftalmologistas - PHELCOM Technologies\" \/>\n<meta property=\"og:description\" content=\"Uma pesquisa realizada pelo Google comprovou que a intelig\u00eancia artificial auxilia os oftalmologistas. Entenda esse estudo e os resultados neste post.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/phelcom.com\/pt-br\/blog\/saude\/inteligencia-artificial-auxilia-os-oftalmologistas\/\" \/>\n<meta property=\"og:site_name\" content=\"PHELCOM Technologies\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/phelcom\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-10T11:55:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-01T19:53:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/phelcom.com\/wp-content\/uploads\/2019\/06\/intelig\u00eancia-artificial-auxilia-oftalmologistas.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"555\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gabriela Marques\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gabriela Marques\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/phelcom.com\\\/pt-br\\\/blog\\\/saude\\\/inteligencia-artificial-auxilia-os-oftalmologistas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/phelcom.com\\\/pt-br\\\/blog\\\/saude\\\/inteligencia-artificial-auxilia-os-oftalmologistas\\\/\"},\"author\":{\"name\":\"Gabriela Marques\",\"@id\":\"https:\\\/\\\/phelcom.com\\\/pt-br\\\/en\\\/#\\\/schema\\\/person\\\/4e0e58359256b5df6d71d632d2fbdd20\"},\"headline\":\"Como a intelig\u00eancia artificial auxilia os oftalmologistas\",\"datePublished\":\"2019-06-10T11:55:43+00:00\",\"dateModified\":\"2023-06-01T19:53:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/phelcom.com\\\/pt-br\\\/blog\\\/saude\\\/inteligencia-artificial-auxilia-os-oftalmologistas\\\/\"},\"wordCount\":668,\"publisher\":{\"@id\":\"https:\\\/\\\/phelcom.com\\\/pt-br\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/phelcom.com\\\/pt-br\\\/blog\\\/saude\\\/inteligencia-artificial-auxilia-os-oftalmologistas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/phelcom.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/intelig\u00eancia-artificial-auxilia-oftalmologistas.jpg\",\"articleSection\":[\"Sa\u00fade\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/phelcom.com\\\/pt-br\\\/blog\\\/saude\\\/inteligencia-artificial-auxilia-os-oftalmologistas\\\/\",\"url\":\"https:\\\/\\\/phelcom.com\\\/pt-br\\\/blog\\\/saude\\\/inteligencia-artificial-auxilia-os-oftalmologistas\\\/\",\"name\":\"Como a intelig\u00eancia artificial auxilia os oftalmologistas - PHELCOM Technologies\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/phelcom.com\\\/pt-br\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/phelcom.com\\\/pt-br\\\/blog\\\/saude\\\/inteligencia-artificial-auxilia-os-oftalmologistas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/phelcom.com\\\/pt-br\\\/blog\\\/saude\\\/inteligencia-artificial-auxilia-os-oftalmologistas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/phelcom.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/intelig\u00eancia-artificial-auxilia-oftalmologistas.jpg\",\"datePublished\":\"2019-06-10T11:55:43+00:00\",\"dateModified\":\"2023-06-01T19:53:45+00:00\",\"description\":\"Uma pesquisa realizada pelo Google comprovou que a intelig\u00eancia artificial auxilia os oftalmologistas. Entenda esse estudo e os resultados neste post.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/phelcom.com\\\/pt-br\\\/blog\\\/saude\\\/inteligencia-artificial-auxilia-os-oftalmologistas\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/phelcom.com\\\/pt-br\\\/blog\\\/saude\\\/inteligencia-artificial-auxilia-os-oftalmologistas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/phelcom.com\\\/pt-br\\\/blog\\\/saude\\\/inteligencia-artificial-auxilia-os-oftalmologistas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/phelcom.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/intelig\u00eancia-artificial-auxilia-oftalmologistas.jpg\",\"contentUrl\":\"https:\\\/\\\/phelcom.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/intelig\u00eancia-artificial-auxilia-oftalmologistas.jpg\",\"width\":1080,\"height\":555,\"caption\":\"intelig\u00eancia artificial auxilia oftalmologistas\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/phelcom.com\\\/pt-br\\\/blog\\\/saude\\\/inteligencia-artificial-auxilia-os-oftalmologistas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/phelcom.com\\\/pt-br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Como a intelig\u00eancia artificial auxilia os oftalmologistas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/phelcom.com\\\/pt-br\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/phelcom.com\\\/pt-br\\\/en\\\/\",\"name\":\"PHELCOM Technologies\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/phelcom.com\\\/pt-br\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/phelcom.com\\\/pt-br\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/phelcom.com\\\/pt-br\\\/en\\\/#organization\",\"name\":\"Phelcom\",\"url\":\"https:\\\/\\\/phelcom.com\\\/pt-br\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/phelcom.com\\\/pt-br\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/phelcom.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/color_horizontal.png\",\"contentUrl\":\"https:\\\/\\\/phelcom.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/color_horizontal.png\",\"width\":245,\"height\":40,\"caption\":\"Phelcom\"},\"image\":{\"@id\":\"https:\\\/\\\/phelcom.com\\\/pt-br\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/phelcom\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/phelcom-technologies\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCSZCLEV9ZrbGBie0R0IxQpA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/phelcom.com\\\/pt-br\\\/en\\\/#\\\/schema\\\/person\\\/4e0e58359256b5df6d71d632d2fbdd20\",\"name\":\"Gabriela Marques\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Como a intelig\u00eancia artificial auxilia os oftalmologistas - PHELCOM Technologies","description":"Uma pesquisa realizada pelo Google comprovou que a intelig\u00eancia artificial auxilia os oftalmologistas. Entenda esse estudo e os resultados neste post.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/phelcom.com\/pt-br\/blog\/saude\/inteligencia-artificial-auxilia-os-oftalmologistas\/","og_locale":"pt_BR","og_type":"article","og_title":"Como a intelig\u00eancia artificial auxilia os oftalmologistas - PHELCOM Technologies","og_description":"Uma pesquisa realizada pelo Google comprovou que a intelig\u00eancia artificial auxilia os oftalmologistas. Entenda esse estudo e os resultados neste post.","og_url":"https:\/\/phelcom.com\/pt-br\/blog\/saude\/inteligencia-artificial-auxilia-os-oftalmologistas\/","og_site_name":"PHELCOM Technologies","article_publisher":"https:\/\/www.facebook.com\/phelcom\/","article_published_time":"2019-06-10T11:55:43+00:00","article_modified_time":"2023-06-01T19:53:45+00:00","og_image":[{"width":1080,"height":555,"url":"https:\/\/phelcom.com\/wp-content\/uploads\/2019\/06\/intelig\u00eancia-artificial-auxilia-oftalmologistas.jpg","type":"image\/jpeg"}],"author":"Gabriela Marques","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Gabriela Marques","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/phelcom.com\/pt-br\/blog\/saude\/inteligencia-artificial-auxilia-os-oftalmologistas\/#article","isPartOf":{"@id":"https:\/\/phelcom.com\/pt-br\/blog\/saude\/inteligencia-artificial-auxilia-os-oftalmologistas\/"},"author":{"name":"Gabriela Marques","@id":"https:\/\/phelcom.com\/pt-br\/en\/#\/schema\/person\/4e0e58359256b5df6d71d632d2fbdd20"},"headline":"Como a intelig\u00eancia artificial auxilia os oftalmologistas","datePublished":"2019-06-10T11:55:43+00:00","dateModified":"2023-06-01T19:53:45+00:00","mainEntityOfPage":{"@id":"https:\/\/phelcom.com\/pt-br\/blog\/saude\/inteligencia-artificial-auxilia-os-oftalmologistas\/"},"wordCount":668,"publisher":{"@id":"https:\/\/phelcom.com\/pt-br\/en\/#organization"},"image":{"@id":"https:\/\/phelcom.com\/pt-br\/blog\/saude\/inteligencia-artificial-auxilia-os-oftalmologistas\/#primaryimage"},"thumbnailUrl":"https:\/\/phelcom.com\/wp-content\/uploads\/2019\/06\/intelig\u00eancia-artificial-auxilia-oftalmologistas.jpg","articleSection":["Sa\u00fade"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/phelcom.com\/pt-br\/blog\/saude\/inteligencia-artificial-auxilia-os-oftalmologistas\/","url":"https:\/\/phelcom.com\/pt-br\/blog\/saude\/inteligencia-artificial-auxilia-os-oftalmologistas\/","name":"Como a intelig\u00eancia artificial auxilia os oftalmologistas - PHELCOM Technologies","isPartOf":{"@id":"https:\/\/phelcom.com\/pt-br\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/phelcom.com\/pt-br\/blog\/saude\/inteligencia-artificial-auxilia-os-oftalmologistas\/#primaryimage"},"image":{"@id":"https:\/\/phelcom.com\/pt-br\/blog\/saude\/inteligencia-artificial-auxilia-os-oftalmologistas\/#primaryimage"},"thumbnailUrl":"https:\/\/phelcom.com\/wp-content\/uploads\/2019\/06\/intelig\u00eancia-artificial-auxilia-oftalmologistas.jpg","datePublished":"2019-06-10T11:55:43+00:00","dateModified":"2023-06-01T19:53:45+00:00","description":"Uma pesquisa realizada pelo Google comprovou que a intelig\u00eancia artificial auxilia os oftalmologistas. Entenda esse estudo e os resultados neste post.","breadcrumb":{"@id":"https:\/\/phelcom.com\/pt-br\/blog\/saude\/inteligencia-artificial-auxilia-os-oftalmologistas\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/phelcom.com\/pt-br\/blog\/saude\/inteligencia-artificial-auxilia-os-oftalmologistas\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/phelcom.com\/pt-br\/blog\/saude\/inteligencia-artificial-auxilia-os-oftalmologistas\/#primaryimage","url":"https:\/\/phelcom.com\/wp-content\/uploads\/2019\/06\/intelig\u00eancia-artificial-auxilia-oftalmologistas.jpg","contentUrl":"https:\/\/phelcom.com\/wp-content\/uploads\/2019\/06\/intelig\u00eancia-artificial-auxilia-oftalmologistas.jpg","width":1080,"height":555,"caption":"intelig\u00eancia artificial auxilia oftalmologistas"},{"@type":"BreadcrumbList","@id":"https:\/\/phelcom.com\/pt-br\/blog\/saude\/inteligencia-artificial-auxilia-os-oftalmologistas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/phelcom.com\/pt-br\/"},{"@type":"ListItem","position":2,"name":"Como a intelig\u00eancia artificial auxilia os oftalmologistas"}]},{"@type":"WebSite","@id":"https:\/\/phelcom.com\/pt-br\/en\/#website","url":"https:\/\/phelcom.com\/pt-br\/en\/","name":"PHELCOM Technologies","description":"","publisher":{"@id":"https:\/\/phelcom.com\/pt-br\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/phelcom.com\/pt-br\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/phelcom.com\/pt-br\/en\/#organization","name":"Phelcom","url":"https:\/\/phelcom.com\/pt-br\/en\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/phelcom.com\/pt-br\/en\/#\/schema\/logo\/image\/","url":"https:\/\/phelcom.com\/wp-content\/uploads\/2018\/07\/color_horizontal.png","contentUrl":"https:\/\/phelcom.com\/wp-content\/uploads\/2018\/07\/color_horizontal.png","width":245,"height":40,"caption":"Phelcom"},"image":{"@id":"https:\/\/phelcom.com\/pt-br\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/phelcom\/","https:\/\/www.linkedin.com\/company\/phelcom-technologies","https:\/\/www.youtube.com\/channel\/UCSZCLEV9ZrbGBie0R0IxQpA"]},{"@type":"Person","@id":"https:\/\/phelcom.com\/pt-br\/en\/#\/schema\/person\/4e0e58359256b5df6d71d632d2fbdd20","name":"Gabriela Marques"}]}},"_links":{"self":[{"href":"https:\/\/phelcom.com\/pt-br\/wp-json\/wp\/v2\/posts\/1551","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/phelcom.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/phelcom.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/phelcom.com\/pt-br\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/phelcom.com\/pt-br\/wp-json\/wp\/v2\/comments?post=1551"}],"version-history":[{"count":0,"href":"https:\/\/phelcom.com\/pt-br\/wp-json\/wp\/v2\/posts\/1551\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/phelcom.com\/pt-br\/wp-json\/wp\/v2\/media\/1553"}],"wp:attachment":[{"href":"https:\/\/phelcom.com\/pt-br\/wp-json\/wp\/v2\/media?parent=1551"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/phelcom.com\/pt-br\/wp-json\/wp\/v2\/categories?post=1551"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/phelcom.com\/pt-br\/wp-json\/wp\/v2\/tags?post=1551"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}