{"id":1082,"date":"2018-12-13T08:51:01","date_gmt":"2018-12-13T10:51:01","guid":{"rendered":"https:\/\/phelcom.com\/?p=1082"},"modified":"2023-06-01T16:31:22","modified_gmt":"2023-06-01T19:31:22","slug":"o-que-e-telemedicina","status":"publish","type":"post","link":"https:\/\/phelcom.com\/pt-br\/blog\/mercado\/o-que-e-telemedicina\/","title":{"rendered":"Entenda o que \u00e9 telemedicina e como funciona"},"content":{"rendered":"<p>Hoje, s\u00e3o inquestion\u00e1veis os in\u00fameros benef\u00edcios da internet na sociedade. Inclusive, na \u00e1rea da sa\u00fade. A ferramenta, aliada aos avan\u00e7os da tecnologia da informa\u00e7\u00e3o e das telecomunica\u00e7\u00f5es, impulsionou o surgimento da telemedicina que, gradualmente, contribui com a democratiza\u00e7\u00e3o do acesso \u00e0 sa\u00fade em comunidades e locais que apresentam d\u00e9ficits em exames, diagn\u00f3sticos e tratamentos de baixa at\u00e9 alta complexidade.<\/p>\n<p>A telemedicina utiliza tecnologia de ponta, por meio de softwares e programas integrados, que permite a realiza\u00e7\u00e3o de servi\u00e7os de sa\u00fade \u00e0 dist\u00e2ncia, como laudos de exames, diagn\u00f3sticos e prescri\u00e7\u00e3o de tratamentos. Isso proporciona acessibilidade, facilidade e rapidez no atendimento, principalmente para pessoas que moram longe dos grandes centros e tem dif\u00edcil acesso \u00e0 sa\u00fade de qualidade.<\/p>\n<p>O objetivo principal \u00e9 n\u00e3o deixar que a dist\u00e2ncia impe\u00e7a o paciente de ter assist\u00eancia m\u00e9dica eficiente e \u00e1gil. Por exemplo, um exame que levaria dias ou semanas para ser feito devido ao encaminhamento, pode ocorrer em minutos com esta especialidade.<\/p>\n<p>Quer saber o que \u00e9 telemedicina, como funciona e as suas principais vantagens? Continue lendo este post.<\/p>\n<h2>O que \u00e9 telemedicina<\/h2>\n<p>A telemedicina \u00e9 uma \u00e1rea da telessa\u00fade que oferece assist\u00eancia m\u00e9dica \u00e0 dist\u00e2ncia, por meio de avan\u00e7ados recursos tecnol\u00f3gicos e Intelig\u00eancia Artificial (IA). Pela internet, \u00e9 poss\u00edvel enviar exames, emitir laudos, fazer diagn\u00f3sticos, prescrever tratamentos e acompanhar a evolu\u00e7\u00e3o do paciente, al\u00e9m de possibilitar a troca de informa\u00e7\u00f5es entre m\u00e9dicos, em plataformas online com acesso pelo computador, celular e tablet.<\/p>\n<p><a href=\"https:\/\/phelcom.com\/wp-content\/uploads\/2018\/12\/O-que-e-telemedicina-1.jpg\" data-lbwps-width=\"1065\" data-lbwps-height=\"560\" data-lbwps-srcsmall=\"https:\/\/phelcom.com\/wp-content\/uploads\/2018\/12\/O-que-e-telemedicina-1-300x158.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1083 aligncenter\" src=\"https:\/\/phelcom.com\/wp-content\/uploads\/2018\/12\/O-que-e-telemedicina-1-300x158.jpg\" alt=\"\" width=\"414\" height=\"218\" srcset=\"https:\/\/phelcom.com\/wp-content\/uploads\/2018\/12\/O-que-e-telemedicina-1-300x158.jpg 300w, https:\/\/phelcom.com\/wp-content\/uploads\/2018\/12\/O-que-e-telemedicina-1-600x315.jpg 600w, https:\/\/phelcom.com\/wp-content\/uploads\/2018\/12\/O-que-e-telemedicina-1-768x404.jpg 768w, https:\/\/phelcom.com\/wp-content\/uploads\/2018\/12\/O-que-e-telemedicina-1-1024x538.jpg 1024w, https:\/\/phelcom.com\/wp-content\/uploads\/2018\/12\/O-que-e-telemedicina-1.jpg 1065w\" sizes=\"(max-width: 414px) 100vw, 414px\" \/><\/a><\/p>\n<p>Esta especialidade apoia a medicina tradicional ao relativizar a no\u00e7\u00e3o de dist\u00e2ncia, levando servi\u00e7os m\u00e9dicos a qualquer lugar e, assim, aumentando o acesso \u00e0 sa\u00fade. Tudo isso de forma mais r\u00e1pida e precisa.<\/p>\n<h2>Como funciona<\/h2>\n<p>Atualmente, a telemedicina \u00e9 subdividida em tr\u00eas \u00e1reas: teleassist\u00eancia, teleduca\u00e7\u00e3o e emiss\u00e3o de laudos \u00e0 dist\u00e2ncia. Em seguida, conhe\u00e7a cada uma delas:<\/p>\n<h3>Teleassist\u00eancia<\/h3>\n<p>Monitora\u00e7\u00e3o do paciente em sua pr\u00f3pria casa ou no hospital. O m\u00e9dico respons\u00e1vel troca informa\u00e7\u00f5es com outros especialistas, como dados de exames e de diversos procedimentos m\u00e9dicos, por meio de plataformas online.<\/p>\n<h3>Teleduca\u00e7\u00e3o<\/h3>\n<p>Capacita\u00e7\u00e3o de profissionais da sa\u00fade que atuam em locais com pouca infraestrutura e dificuldade de acesso \u00e0s atualiza\u00e7\u00f5es da \u00e1rea.<\/p>\n<h3>Emiss\u00e3o de laudos \u00e0 dist\u00e2ncia<\/h3>\n<p>Sem d\u00favida, \u00e9 a principal frente da telemedicina e a que mais cresce no Brasil. O exame pode ser feito em qualquer lugar e laudado por m\u00e9dicos &#8211; que tamb\u00e9m podem estar em qualquer localiza\u00e7\u00e3o \u2013 por meio de softwares online com acesso via computador, celular ou tablet.<\/p>\n<p>Apesar de utilizar tecnologia de ponta, a telemedicina \u00e9 uma modalidade pr\u00e1tica e simples. Al\u00e9m disso, gera in\u00fameros benef\u00edcios para pacientes e profissionais.<\/p>\n<h2>Vantagens<\/h2>\n<p>A diminui\u00e7\u00e3o da dist\u00e2ncia, com acesso de qualidade a servi\u00e7os na \u00e1rea de sa\u00fade, com toda a certeza \u00e9 uma das principais vantagens da telemedicina. Mas, h\u00e1 muito mais:<\/p>\n<ul>\n<li>Aumento do contato e troca de informa\u00e7\u00f5es entre m\u00e9dico e paciente, gerando tamb\u00e9m maior acolhimento;<\/li>\n<li>Democratiza\u00e7\u00e3o do acesso \u00e0 sa\u00fade, principalmente em locais com pouca infraestrutura de servi\u00e7os de qualidade na \u00e1rea, como m\u00e9dicos, profissionais de sa\u00fade, equipamentos, medicamentos etc;<\/li>\n<li>Maior rapidez no atendimento, por meio de sistemas informatizados integrados a plataformas online com acesso via computadores, celulares e tablets;<\/li>\n<li>Garantia de seguran\u00e7a e sigilo de dados;<\/li>\n<li>Acesso a especialistas e profissionais de refer\u00eancia;<\/li>\n<li>Redu\u00e7\u00e3o do tempo de atendimento e de custos operacionais;<\/li>\n<li>Facilidade na troca de informa\u00e7\u00f5es entre os servi\u00e7os de sa\u00fade;<\/li>\n<li>Diminui\u00e7\u00e3o do deslocamento de pacientes a hospitais e grandes centros urbanos;<\/li>\n<li>Facilidade na realiza\u00e7\u00e3o de exames, que podem ser feitos em cl\u00ednicas e postos de sa\u00fade;<\/li>\n<li>Melhora na qualidade dos laudos emitidos;<\/li>\n<li>Acesso \u00e0s capacita\u00e7\u00f5es e atualiza\u00e7\u00f5es para os profissionais da sa\u00fade.<\/li>\n<\/ul>\n<h2><\/h2>\n<h2><\/h2>\n<h2>Telemedicina na oftalmologia<\/h2>\n<p>A oftalmologia \u00e9 uma das especialidades atendidas pela telemedicina. Por exemplo, exames podem ser feitos por um profissional da sa\u00fade \u2013 que n\u00e3o necessariamente um m\u00e9dico oftalmologista \u2013 e enviado online para ser laudado por um especialista. Dentre eles, est\u00e3o exames de retina e de acuidade visual. Eles verificam poss\u00edveis desgastes de vis\u00e3o e avaliam a capacidade do paciente em enxergar com clareza.<\/p>\n<p>Hoje, h\u00e1 aparelhos port\u00e1teis acoplados a smartphones e integrados a plataformas online que possibilitam realizar exames de retina a baixo custo e ter o laudo emitido por um especialista de centros de excel\u00eancia m\u00e9dica, por exemplo.<\/p>\n<p><a href=\"https:\/\/phelcom.com\/wp-content\/uploads\/2018\/12\/O-que-e-telemedicina-3.png\" data-lbwps-width=\"720\" data-lbwps-height=\"1280\" data-lbwps-srcsmall=\"https:\/\/phelcom.com\/wp-content\/uploads\/2018\/12\/O-que-e-telemedicina-3-169x300.png\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-1084 aligncenter\" src=\"https:\/\/phelcom.com\/wp-content\/uploads\/2018\/12\/O-que-e-telemedicina-3-169x300.png\" alt=\"\" width=\"240\" height=\"426\" srcset=\"https:\/\/phelcom.com\/wp-content\/uploads\/2018\/12\/O-que-e-telemedicina-3-169x300.png 169w, https:\/\/phelcom.com\/wp-content\/uploads\/2018\/12\/O-que-e-telemedicina-3-600x1067.png 600w, https:\/\/phelcom.com\/wp-content\/uploads\/2018\/12\/O-que-e-telemedicina-3-576x1024.png 576w, https:\/\/phelcom.com\/wp-content\/uploads\/2018\/12\/O-que-e-telemedicina-3.png 720w\" sizes=\"(max-width: 240px) 100vw, 240px\" \/><\/a><\/p>\n<p style=\"text-align: center;\">Exame de retina feito com o retin\u00f3grafo port\u00e1til Phelcom Eyer.<\/p>\n<h2><\/h2>\n<h2>Conclus\u00e3o<\/h2>\n<p>De fato, a telemedicina tem o potencial de melhorar e democratizar o acesso \u00e0 sa\u00fade no Brasil e no mundo. Ela n\u00e3o veio para substituir a medicina tradicional, mas aperfei\u00e7o\u00e1-la e transpor barreiras socioecon\u00f4micas e geogr\u00e1ficas. Tudo isso em busca de oferecer sa\u00fade de qualidade para todos.<\/p>\n<p>Receba mais informa\u00e7\u00f5es sobre telemedicina e a democratiza\u00e7\u00e3o do acesso \u00e0 sa\u00fade. Assine a nossa newsletter.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Essa especialidade contribui com a democratiza\u00e7\u00e3o do acesso \u00e0 sa\u00fade em comunidades e locais que apresentam d\u00e9ficits em exames, diagn\u00f3sticos e tratamentos de baixa at\u00e9 alta complexidade. <\/p>\n","protected":false},"author":3,"featured_media":1102,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[105],"tags":[],"class_list":["post-1082","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mercado"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Entenda o que \u00e9 telemedicina e como funciona - PHELCOM Technologies<\/title>\n<meta name=\"description\" content=\"Entenda neste post o que \u00e9 telemedicina, como funciona, os benef\u00edcios e o futuro dessa \u00e1rea que s\u00f3 avan\u00e7a em todo o mundo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/phelcom.com\/pt-br\/blog\/mercado\/o-que-e-telemedicina\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Entenda o que \u00e9 telemedicina e como funciona - PHELCOM Technologies\" \/>\n<meta property=\"og:description\" content=\"Entenda neste post o que \u00e9 telemedicina, como funciona, os benef\u00edcios e o futuro dessa \u00e1rea que s\u00f3 avan\u00e7a em todo o mundo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/phelcom.com\/pt-br\/blog\/mercado\/o-que-e-telemedicina\/\" \/>\n<meta property=\"og:site_name\" content=\"PHELCOM Technologies\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/phelcom\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-12-13T10:51:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-01T19:31:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/phelcom.com\/wp-content\/uploads\/2018\/12\/O-que-e-telemedicina-4-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"554\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gabriela Marques\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gabriela Marques\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/phelcom.com\\\/pt-br\\\/blog\\\/mercado\\\/o-que-e-telemedicina\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/phelcom.com\\\/pt-br\\\/blog\\\/mercado\\\/o-que-e-telemedicina\\\/\"},\"author\":{\"name\":\"Gabriela Marques\",\"@id\":\"https:\\\/\\\/phelcom.com\\\/pt-br\\\/en\\\/#\\\/schema\\\/person\\\/4e0e58359256b5df6d71d632d2fbdd20\"},\"headline\":\"Entenda o que \u00e9 telemedicina e como funciona\",\"datePublished\":\"2018-12-13T10:51:01+00:00\",\"dateModified\":\"2023-06-01T19:31:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/phelcom.com\\\/pt-br\\\/blog\\\/mercado\\\/o-que-e-telemedicina\\\/\"},\"wordCount\":868,\"publisher\":{\"@id\":\"https:\\\/\\\/phelcom.com\\\/pt-br\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/phelcom.com\\\/pt-br\\\/blog\\\/mercado\\\/o-que-e-telemedicina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/phelcom.com\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/O-que-e-telemedicina-4-2.jpg\",\"articleSection\":[\"Mercado\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/phelcom.com\\\/pt-br\\\/blog\\\/mercado\\\/o-que-e-telemedicina\\\/\",\"url\":\"https:\\\/\\\/phelcom.com\\\/pt-br\\\/blog\\\/mercado\\\/o-que-e-telemedicina\\\/\",\"name\":\"Entenda o que \u00e9 telemedicina e como funciona - PHELCOM Technologies\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/phelcom.com\\\/pt-br\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/phelcom.com\\\/pt-br\\\/blog\\\/mercado\\\/o-que-e-telemedicina\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/phelcom.com\\\/pt-br\\\/blog\\\/mercado\\\/o-que-e-telemedicina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/phelcom.com\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/O-que-e-telemedicina-4-2.jpg\",\"datePublished\":\"2018-12-13T10:51:01+00:00\",\"dateModified\":\"2023-06-01T19:31:22+00:00\",\"description\":\"Entenda neste post o que \u00e9 telemedicina, como funciona, os benef\u00edcios e o futuro dessa \u00e1rea que s\u00f3 avan\u00e7a em todo o mundo.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/phelcom.com\\\/pt-br\\\/blog\\\/mercado\\\/o-que-e-telemedicina\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/phelcom.com\\\/pt-br\\\/blog\\\/mercado\\\/o-que-e-telemedicina\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/phelcom.com\\\/pt-br\\\/blog\\\/mercado\\\/o-que-e-telemedicina\\\/#primaryimage\",\"url\":\"https:\\\/\\\/phelcom.com\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/O-que-e-telemedicina-4-2.jpg\",\"contentUrl\":\"https:\\\/\\\/phelcom.com\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/O-que-e-telemedicina-4-2.jpg\",\"width\":1080,\"height\":554,\"caption\":\"O que \u00e9 telemedicina\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/phelcom.com\\\/pt-br\\\/blog\\\/mercado\\\/o-que-e-telemedicina\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/phelcom.com\\\/pt-br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Entenda o que \u00e9 telemedicina e como funciona\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/phelcom.com\\\/pt-br\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/phelcom.com\\\/pt-br\\\/en\\\/\",\"name\":\"PHELCOM Technologies\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/phelcom.com\\\/pt-br\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/phelcom.com\\\/pt-br\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/phelcom.com\\\/pt-br\\\/en\\\/#organization\",\"name\":\"Phelcom\",\"url\":\"https:\\\/\\\/phelcom.com\\\/pt-br\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/phelcom.com\\\/pt-br\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/phelcom.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/color_horizontal.png\",\"contentUrl\":\"https:\\\/\\\/phelcom.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/color_horizontal.png\",\"width\":245,\"height\":40,\"caption\":\"Phelcom\"},\"image\":{\"@id\":\"https:\\\/\\\/phelcom.com\\\/pt-br\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/phelcom\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/phelcom-technologies\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCSZCLEV9ZrbGBie0R0IxQpA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/phelcom.com\\\/pt-br\\\/en\\\/#\\\/schema\\\/person\\\/4e0e58359256b5df6d71d632d2fbdd20\",\"name\":\"Gabriela Marques\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Entenda o que \u00e9 telemedicina e como funciona - PHELCOM Technologies","description":"Entenda neste post o que \u00e9 telemedicina, como funciona, os benef\u00edcios e o futuro dessa \u00e1rea que s\u00f3 avan\u00e7a em todo o mundo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/phelcom.com\/pt-br\/blog\/mercado\/o-que-e-telemedicina\/","og_locale":"pt_BR","og_type":"article","og_title":"Entenda o que \u00e9 telemedicina e como funciona - PHELCOM Technologies","og_description":"Entenda neste post o que \u00e9 telemedicina, como funciona, os benef\u00edcios e o futuro dessa \u00e1rea que s\u00f3 avan\u00e7a em todo o mundo.","og_url":"https:\/\/phelcom.com\/pt-br\/blog\/mercado\/o-que-e-telemedicina\/","og_site_name":"PHELCOM Technologies","article_publisher":"https:\/\/www.facebook.com\/phelcom\/","article_published_time":"2018-12-13T10:51:01+00:00","article_modified_time":"2023-06-01T19:31:22+00:00","og_image":[{"width":1080,"height":554,"url":"https:\/\/phelcom.com\/wp-content\/uploads\/2018\/12\/O-que-e-telemedicina-4-2.jpg","type":"image\/jpeg"}],"author":"Gabriela Marques","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Gabriela Marques","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/phelcom.com\/pt-br\/blog\/mercado\/o-que-e-telemedicina\/#article","isPartOf":{"@id":"https:\/\/phelcom.com\/pt-br\/blog\/mercado\/o-que-e-telemedicina\/"},"author":{"name":"Gabriela Marques","@id":"https:\/\/phelcom.com\/pt-br\/en\/#\/schema\/person\/4e0e58359256b5df6d71d632d2fbdd20"},"headline":"Entenda o que \u00e9 telemedicina e como funciona","datePublished":"2018-12-13T10:51:01+00:00","dateModified":"2023-06-01T19:31:22+00:00","mainEntityOfPage":{"@id":"https:\/\/phelcom.com\/pt-br\/blog\/mercado\/o-que-e-telemedicina\/"},"wordCount":868,"publisher":{"@id":"https:\/\/phelcom.com\/pt-br\/en\/#organization"},"image":{"@id":"https:\/\/phelcom.com\/pt-br\/blog\/mercado\/o-que-e-telemedicina\/#primaryimage"},"thumbnailUrl":"https:\/\/phelcom.com\/wp-content\/uploads\/2018\/12\/O-que-e-telemedicina-4-2.jpg","articleSection":["Mercado"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/phelcom.com\/pt-br\/blog\/mercado\/o-que-e-telemedicina\/","url":"https:\/\/phelcom.com\/pt-br\/blog\/mercado\/o-que-e-telemedicina\/","name":"Entenda o que \u00e9 telemedicina e como funciona - PHELCOM Technologies","isPartOf":{"@id":"https:\/\/phelcom.com\/pt-br\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/phelcom.com\/pt-br\/blog\/mercado\/o-que-e-telemedicina\/#primaryimage"},"image":{"@id":"https:\/\/phelcom.com\/pt-br\/blog\/mercado\/o-que-e-telemedicina\/#primaryimage"},"thumbnailUrl":"https:\/\/phelcom.com\/wp-content\/uploads\/2018\/12\/O-que-e-telemedicina-4-2.jpg","datePublished":"2018-12-13T10:51:01+00:00","dateModified":"2023-06-01T19:31:22+00:00","description":"Entenda neste post o que \u00e9 telemedicina, como funciona, os benef\u00edcios e o futuro dessa \u00e1rea que s\u00f3 avan\u00e7a em todo o mundo.","breadcrumb":{"@id":"https:\/\/phelcom.com\/pt-br\/blog\/mercado\/o-que-e-telemedicina\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/phelcom.com\/pt-br\/blog\/mercado\/o-que-e-telemedicina\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/phelcom.com\/pt-br\/blog\/mercado\/o-que-e-telemedicina\/#primaryimage","url":"https:\/\/phelcom.com\/wp-content\/uploads\/2018\/12\/O-que-e-telemedicina-4-2.jpg","contentUrl":"https:\/\/phelcom.com\/wp-content\/uploads\/2018\/12\/O-que-e-telemedicina-4-2.jpg","width":1080,"height":554,"caption":"O que \u00e9 telemedicina"},{"@type":"BreadcrumbList","@id":"https:\/\/phelcom.com\/pt-br\/blog\/mercado\/o-que-e-telemedicina\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/phelcom.com\/pt-br\/"},{"@type":"ListItem","position":2,"name":"Entenda o que \u00e9 telemedicina e como funciona"}]},{"@type":"WebSite","@id":"https:\/\/phelcom.com\/pt-br\/en\/#website","url":"https:\/\/phelcom.com\/pt-br\/en\/","name":"PHELCOM Technologies","description":"","publisher":{"@id":"https:\/\/phelcom.com\/pt-br\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/phelcom.com\/pt-br\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/phelcom.com\/pt-br\/en\/#organization","name":"Phelcom","url":"https:\/\/phelcom.com\/pt-br\/en\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/phelcom.com\/pt-br\/en\/#\/schema\/logo\/image\/","url":"https:\/\/phelcom.com\/wp-content\/uploads\/2018\/07\/color_horizontal.png","contentUrl":"https:\/\/phelcom.com\/wp-content\/uploads\/2018\/07\/color_horizontal.png","width":245,"height":40,"caption":"Phelcom"},"image":{"@id":"https:\/\/phelcom.com\/pt-br\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/phelcom\/","https:\/\/www.linkedin.com\/company\/phelcom-technologies","https:\/\/www.youtube.com\/channel\/UCSZCLEV9ZrbGBie0R0IxQpA"]},{"@type":"Person","@id":"https:\/\/phelcom.com\/pt-br\/en\/#\/schema\/person\/4e0e58359256b5df6d71d632d2fbdd20","name":"Gabriela Marques"}]}},"_links":{"self":[{"href":"https:\/\/phelcom.com\/pt-br\/wp-json\/wp\/v2\/posts\/1082","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/phelcom.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/phelcom.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/phelcom.com\/pt-br\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/phelcom.com\/pt-br\/wp-json\/wp\/v2\/comments?post=1082"}],"version-history":[{"count":0,"href":"https:\/\/phelcom.com\/pt-br\/wp-json\/wp\/v2\/posts\/1082\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/phelcom.com\/pt-br\/wp-json\/wp\/v2\/media\/1102"}],"wp:attachment":[{"href":"https:\/\/phelcom.com\/pt-br\/wp-json\/wp\/v2\/media?parent=1082"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/phelcom.com\/pt-br\/wp-json\/wp\/v2\/categories?post=1082"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/phelcom.com\/pt-br\/wp-json\/wp\/v2\/tags?post=1082"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}